{"id":3995,"date":"2019-03-23T11:38:52","date_gmt":"2019-03-23T11:38:52","guid":{"rendered":"https:\/\/openskycharity.international\/product\/dvd-pointless-joy-of-freedom\/"},"modified":"2025-12-16T12:30:35","modified_gmt":"2025-12-16T12:30:35","slug":"dvd-grundlos-glucklich","status":"publish","type":"product","link":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/","title":{"rendered":"DVD Grundlos gl\u00fccklich"},"content":{"rendered":"<div style=\"padding:56.25% 0 0 0;position:relative;\"><iframe src=\"https:\/\/player.vimeo.com\/video\/492194999?title=0&amp;byline=0&amp;portrait=0&amp;badge=0&amp;autopause=0&amp;player_id=0&amp;app_id=58479\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\" style=\"position:absolute;top:0;left:0;width:100%;height:100%;\" title=\"Grundlos gl\u00fccklich - Die Freiheit des Seins\"><\/iframe><\/div>\n<p><script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script><\/p>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<div align=\"justify\">\n<div align=\"left\">\n<p align=\"justify\">Dieser Film gibt einen Einblick in das Leben und Werk des englischen spirituellen Lehrers John David, in seinen facettenreichen Ansatz zur Freiheit und wie er mit den Menschen arbeitet, die mit ihm in den Open Sky House Gemeinschaften leben. Er nimmt den Zuschauer mit auf eine Reise durch die spirituelle Welt, beginnend mit der Neugier auf sich selbst bis zum Verstehen, was wahre Freiheit ist.<\/p>\n<p><i>DVD mit Untertiteln: Deutsch, Franz\u00f6sisch, Italienisch, Spanisch, Russisch<\/i><\/p>\n<p><a href=\"https:\/\/openskycharity.international\/de\/produkt\/filmdownload-grundlos-glucklich\/\"><i><u><b>Auch als Download erh\u00e4ltlich. Hier klicken<\/b><\/u><\/i><\/a><\/p>\n<h3><\/h3>\n<\/div>\n<\/div>\n","protected":false},"featured_media":5033,"comment_status":"open","ping_status":"closed","template":"","meta":{"postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""}},"product_brand":[],"product_cat":[388,777,778],"product_tag":[372,438,471,400,440,375,484,581,376,377,378,379,380,382],"class_list":{"0":"post-3995","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-filme","7":"product_cat-john-david-dvds","8":"product_cat-open-sky-press-filme","9":"product_tag-advaita-de","10":"product_tag-freiheit","11":"product_tag-gangaji-de","12":"product_tag-gemeinschaft","13":"product_tag-gluck","14":"product_tag-john-david-de","15":"product_tag-mooji-de","16":"product_tag-open-sky-press-de","17":"product_tag-philosophie-de","18":"product_tag-premananda-de","19":"product_tag-ramana-maharshi-de","20":"product_tag-satsang-de","21":"product_tag-spirituality-de","22":"product_tag-who-am-i-de","24":"first","25":"instock","26":"taxable","27":"shipping-taxable","28":"purchasable","29":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DVD Grundlos gl\u00fccklich - Spiritual Books &amp; Films Online Shop #1 | Open Sky Press DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DVD Grundlos gl\u00fccklich - Spiritual Books &amp; Films Online Shop #1 | Open Sky Press DE\" \/>\n<meta property=\"og:description\" content=\"Dieser Film gibt einen Einblick in das Leben und Werk des englischen spirituellen Lehrers John David, in seinen facettenreichen Ansatz zur Freiheit und wie er mit den Menschen arbeitet, die mit ihm in den Open Sky House Gemeinschaften leben. Er nimmt den Zuschauer mit auf eine Reise durch die spirituelle Welt, beginnend mit der Neugier auf sich selbst bis zum Verstehen, was wahre Freiheit ist.  DVD mit Untertiteln: Deutsch, Franz\u00f6sisch, Italienisch, Spanisch, Russisch  Auch als Download erh\u00e4ltlich. Hier klicken\" \/>\n<meta property=\"og:url\" content=\"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/\" \/>\n<meta property=\"og:site_name\" content=\"Spiritual Books &amp; Films Online Shop #1 | Open Sky Press DE\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T12:30:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/openskypress.com\/wp-content\/uploads\/2019\/05\/film-grundlos-gluecklich-de.png\" \/>\n\t<meta property=\"og:image:width\" content=\"490\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/openskypress.com\\\/de\\\/product\\\/dvd-grundlos-glucklich\\\/\",\"url\":\"https:\\\/\\\/openskypress.com\\\/de\\\/product\\\/dvd-grundlos-glucklich\\\/\",\"name\":\"DVD Grundlos gl\u00fccklich - Spiritual Books &amp; Films Online Shop #1 | Open Sky Press DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/openskypress.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/openskypress.com\\\/de\\\/product\\\/dvd-grundlos-glucklich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/openskypress.com\\\/de\\\/product\\\/dvd-grundlos-glucklich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/openskypress.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/film-grundlos-gluecklich-de.png\",\"datePublished\":\"2019-03-23T11:38:52+00:00\",\"dateModified\":\"2025-12-16T12:30:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/openskypress.com\\\/de\\\/product\\\/dvd-grundlos-glucklich\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/openskypress.com\\\/de\\\/product\\\/dvd-grundlos-glucklich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/openskypress.com\\\/de\\\/product\\\/dvd-grundlos-glucklich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/openskypress.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/film-grundlos-gluecklich-de.png\",\"contentUrl\":\"https:\\\/\\\/openskypress.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/film-grundlos-gluecklich-de.png\",\"width\":490,\"height\":740,\"caption\":\"grundlos gl\u00fccklich, john david, die freiheit des seins\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/openskypress.com\\\/de\\\/product\\\/dvd-grundlos-glucklich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/openskypress.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/openskypress.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DVD Grundlos gl\u00fccklich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/openskypress.com\\\/#website\",\"url\":\"https:\\\/\\\/openskypress.com\\\/\",\"name\":\"Spiritual Books & Films Online Shop #1 | Open Sky Press\",\"description\":\"Best store of Books &amp; DVDs about Satsang, Indian &amp; Western philosophy &amp; yoga. Spiritual teachers talks about awakening, enlightenment and mindfulness\",\"publisher\":{\"@id\":\"https:\\\/\\\/openskypress.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/openskypress.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/openskypress.com\\\/#organization\",\"name\":\"Spiritual Books & Films Online Shop #1 | Open Sky Press\",\"url\":\"https:\\\/\\\/openskypress.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/openskypress.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/openskypress.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-osp-1.png\",\"contentUrl\":\"https:\\\/\\\/openskypress.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-osp-1.png\",\"width\":222,\"height\":219,\"caption\":\"Spiritual Books & Films Online Shop #1 | Open Sky Press\"},\"image\":{\"@id\":\"https:\\\/\\\/openskypress.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DVD Grundlos gl\u00fccklich - Spiritual Books &amp; Films Online Shop #1 | Open Sky Press DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/","og_locale":"de_DE","og_type":"article","og_title":"DVD Grundlos gl\u00fccklich - Spiritual Books &amp; Films Online Shop #1 | Open Sky Press DE","og_description":"Dieser Film gibt einen Einblick in das Leben und Werk des englischen spirituellen Lehrers John David, in seinen facettenreichen Ansatz zur Freiheit und wie er mit den Menschen arbeitet, die mit ihm in den Open Sky House Gemeinschaften leben. Er nimmt den Zuschauer mit auf eine Reise durch die spirituelle Welt, beginnend mit der Neugier auf sich selbst bis zum Verstehen, was wahre Freiheit ist.  DVD mit Untertiteln: Deutsch, Franz\u00f6sisch, Italienisch, Spanisch, Russisch  Auch als Download erh\u00e4ltlich. Hier klicken","og_url":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/","og_site_name":"Spiritual Books &amp; Films Online Shop #1 | Open Sky Press DE","article_modified_time":"2025-12-16T12:30:35+00:00","og_image":[{"width":490,"height":740,"url":"https:\/\/openskypress.com\/wp-content\/uploads\/2019\/05\/film-grundlos-gluecklich-de.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/","url":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/","name":"DVD Grundlos gl\u00fccklich - Spiritual Books &amp; Films Online Shop #1 | Open Sky Press DE","isPartOf":{"@id":"https:\/\/openskypress.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/#primaryimage"},"image":{"@id":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/#primaryimage"},"thumbnailUrl":"https:\/\/openskypress.com\/wp-content\/uploads\/2019\/05\/film-grundlos-gluecklich-de.png","datePublished":"2019-03-23T11:38:52+00:00","dateModified":"2025-12-16T12:30:35+00:00","breadcrumb":{"@id":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/#primaryimage","url":"https:\/\/openskypress.com\/wp-content\/uploads\/2019\/05\/film-grundlos-gluecklich-de.png","contentUrl":"https:\/\/openskypress.com\/wp-content\/uploads\/2019\/05\/film-grundlos-gluecklich-de.png","width":490,"height":740,"caption":"grundlos gl\u00fccklich, john david, die freiheit des seins"},{"@type":"BreadcrumbList","@id":"https:\/\/openskypress.com\/de\/product\/dvd-grundlos-glucklich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/openskypress.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/openskypress.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"DVD Grundlos gl\u00fccklich"}]},{"@type":"WebSite","@id":"https:\/\/openskypress.com\/#website","url":"https:\/\/openskypress.com\/","name":"Spiritual Books & Films Online Shop #1 | Open Sky Press","description":"Best store of Books &amp; DVDs about Satsang, Indian &amp; Western philosophy &amp; yoga. Spiritual teachers talks about awakening, enlightenment and mindfulness","publisher":{"@id":"https:\/\/openskypress.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/openskypress.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/openskypress.com\/#organization","name":"Spiritual Books & Films Online Shop #1 | Open Sky Press","url":"https:\/\/openskypress.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/openskypress.com\/#\/schema\/logo\/image\/","url":"https:\/\/openskypress.com\/wp-content\/uploads\/2020\/02\/logo-osp-1.png","contentUrl":"https:\/\/openskypress.com\/wp-content\/uploads\/2020\/02\/logo-osp-1.png","width":222,"height":219,"caption":"Spiritual Books & Films Online Shop #1 | Open Sky Press"},"image":{"@id":"https:\/\/openskypress.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/openskypress.com\/de\/wp-json\/wp\/v2\/product\/3995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/openskypress.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/openskypress.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/openskypress.com\/de\/wp-json\/wp\/v2\/comments?post=3995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/openskypress.com\/de\/wp-json\/wp\/v2\/media\/5033"}],"wp:attachment":[{"href":"https:\/\/openskypress.com\/de\/wp-json\/wp\/v2\/media?parent=3995"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/openskypress.com\/de\/wp-json\/wp\/v2\/product_brand?post=3995"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/openskypress.com\/de\/wp-json\/wp\/v2\/product_cat?post=3995"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/openskypress.com\/de\/wp-json\/wp\/v2\/product_tag?post=3995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}